{"id":524,"date":"2014-10-26T09:59:24","date_gmt":"2014-10-26T09:59:24","guid":{"rendered":"https:\/\/www.rundwanderung-lagomera.de\/?p=524"},"modified":"2019-12-22T18:35:31","modified_gmt":"2019-12-22T17:35:31","slug":"etape-6-directions","status":"publish","type":"post","link":"https:\/\/www.rundwanderung-lagomera.de\/fr\/etappe-6-wegbeschreibung\/","title":{"rendered":"\u00c9tape 6 : Itin\u00e9raire"},"content":{"rendered":"<div id=\"pl-524\"  class=\"panel-layout\" ><div id=\"pg-524-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-524-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-524-0-0-0\" class=\"so-panel widget widget_metaslider_widget panel-first-child panel-last-child\" data-index=\"0\" ><div id=\"metaslider-id-315\" style=\"width: 100%;\" class=\"ml-slider-3-110-0 metaslider metaslider-flex metaslider-315 ml-slider has-dots-nav ms-theme-simply-dark\" role=\"region\" aria-label=\"\u00e9tape 6\" data-height=\"270\" data-width=\"1024\">\n    <div id=\"metaslider_container_315\">\n        <div id=\"metaslider_315\">\n            <ul class='slides'>\n                <li style=\"display: block; width: 100%;\" class=\"slide-1824 ms-image\" aria-roledescription=\"slide\" data-date=\"2016-01-24 20:49:08\" data-filename=\"rundwanderweg-la-gomera-etappe-6-aufstieg-1024x270.jpg\" data-slide-type=\"image\"><a href=\"https:\/\/www.rundwanderung-lagomera.de\/wp-content\/uploads\/2016\/01\/rundwanderweg-la-gomera-etappe-6-aufstieg.jpg\" target=\"_self\" aria-label=\"Voir les d\u00e9tails de la diapositive\" class=\"metaslider_image_link\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rundwanderung-lagomera.de\/wp-content\/uploads\/2016\/01\/rundwanderweg-la-gomera-etappe-6-aufstieg-1024x270.jpg\" height=\"270\" width=\"1024\" alt=\"\" class=\"slider-315 slide-1824 msDefaultImage\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\">Ascension depuis la plage &quot;Playa de la Guancha&quot;<\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-1823 ms-image\" aria-roledescription=\"slide\" data-date=\"2016-01-24 20:49:05\" data-filename=\"rundwanderweg-la-gomera-etappe-6-weggabelung-1024x270.jpg\" data-slide-type=\"image\"><a href=\"https:\/\/www.rundwanderung-lagomera.de\/wp-content\/uploads\/2016\/01\/rundwanderweg-la-gomera-etappe-6-weggabelung.jpg\" target=\"_self\" aria-label=\"Voir les d\u00e9tails de la diapositive\" class=\"metaslider_image_link\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rundwanderung-lagomera.de\/wp-content\/uploads\/2016\/01\/rundwanderweg-la-gomera-etappe-6-weggabelung-1024x270.jpg\" height=\"270\" width=\"1024\" alt=\"\" class=\"slider-315 slide-1823 msDefaultImage\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\">Bifurcation sur la route de &quot;Playa el Cabrito&quot;<\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-1822 ms-image\" aria-roledescription=\"slide\" data-date=\"2016-01-24 20:49:02\" data-filename=\"rundwanderweg-la-gomera-etappe-6-h\u00f6chster-punkt-1024x270.jpg\" data-slide-type=\"image\"><a href=\"https:\/\/www.rundwandern-lagomera.de\/wp-content\/uploads\/2016\/01\/rundwanderweg-la-gomera-etappe-6-h\u00f6her-punkt.jpg\" target=\"_self\" aria-label=\"Voir les d\u00e9tails de la diapositive\" class=\"metaslider_image_link\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rundwanderung-lagomera.de\/wp-content\/uploads\/2016\/01\/rundwanderweg-la-gomera-etappe-6-h\u00f6chster-punkt-1024x270.jpg\" height=\"270\" width=\"1024\" alt=\"\" class=\"slider-315 slide-1822 msDefaultImage\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\">Vue depuis le point le plus haut de la sc\u00e8ne<\/div><\/div><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-524-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-524-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-524-1-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"1\" >\t\t\t<div class=\"textwidget\"><p>Aujourd&#039;hui est le dernier jour de notre randonn\u00e9e circulaire et \u00e0 environ 21 km nous avons devant nous la plus longue des six \u00e9tapes !<br \/>\n<b>Notre conseil :<\/b> Si vous partez \u00e0 l&#039;heure aujourd&#039;hui, vous pouvez prendre le bus ou le ferry pour retourner \u00e0 Saint-S\u00e9bastien \u00e0 la destination de l&#039;\u00e9tape - en d&#039;autres termes\u00a0: nous pouvons laisser une partie de nos bagages \u00e0 l&#039;h\u00f4tel si nous planifions la nuit en cons\u00e9quence.<br \/>\nHoraires de d\u00e9part de la ligne de bus 3 \u00e0 Playa den Santiago retour \u00e0 San Sebasti\u00e1n de la Gomera (\u00e0 partir de janvier 2016) : du lundi au samedi 15h30 et 19h00, dimanches et jours f\u00e9ri\u00e9s uniquement 17h30. Heures de d\u00e9part actuelles\u00a0: <a href=\"http:\/\/www.guaguagomera.com\" target=\"_blank\" rel=\"noopener\">www.guaguagomera.com<\/a>.<br \/>\nR\u00e9cemment, il a \u00e9galement \u00e9t\u00e9 possible de reprendre le ferry \u00e0 San Sebasti\u00e1n de la Gomera, puisque Fred Olsen a \u00e9largi le service de ferry - un grand merci \u00e0 Tamara et Simona pour l&#039;avoir signal\u00e9 ! Les heures de d\u00e9part actuelles peuvent \u00eatre trouv\u00e9es ici: <a href=\"https:\/\/www.fredolsen.es\/en\" target=\"_blank\" rel=\"noopener\">https:\/\/www.fredolsen.es\/en<\/a> (A partir de f\u00e9vrier 2018, 3 liaisons quotidiennes, dernier d\u00e9part \u00e0 19h40).<\/p>\n<p><b>Danger:<\/b> il n&#039;y a pas de magasins sur le chemin et presque pas d&#039;ombre sur le parcours ! Il est conseill\u00e9 d&#039;emporter suffisamment d&#039;eau avec vous !<\/p>\n<p>Notre randonn\u00e9e commence \u00e0 la courte promenade de la plage de San Sebasti\u00e1n en direction du sud-ouest. Imm\u00e9diatement apr\u00e8s le terrain de sport bleu (waypoint 1), nous tournons \u00e0 droite sur une route de gravier et marchons vers la centrale \u00e9lectrique de La Gomera. Juste derri\u00e8re (waypoint 2) le GR-132 monte la pente vers la gauche.<br \/>\nBient\u00f4t les derni\u00e8res maisons ont disparu de notre champ de vision et nous ne sommes plus entour\u00e9s que par l&#039;impressionnant paysage de pierre, de buissons divers, de marguerites et d&#039;une vue interminable sur la mer.<\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-524-1-1\"  class=\"panel-grid-cell\" ><div id=\"panel-524-1-1-0\" class=\"so-panel widget widget_text panel-first-child\" data-index=\"2\" ><h3 class=\"widget-title\">Faits sur l&#039;\u00e9tape 6<\/h3>\t\t\t<div class=\"textwidget\"><p><b>Altitude:<\/b> 1140m de mont\u00e9e \/ 1140m de descente<br \/>\n<b>Itin\u00e9raire:<\/b> 21 km<br \/>\n<b>Dur\u00e9e:<\/b> 7h30 (sans pauses)  <\/p>\n<\/div>\n\t\t<\/div><div id=\"panel-524-1-1-1\" class=\"so-panel widget widget_edd_product_details\" data-index=\"3\" ><h3 class=\"widget-title\">T\u00e9l\u00e9chargement de l&#039;itin\u00e9raire - \u00c9tape 6 (fichier GPX)<\/h3>\t<form id=\"edd_purchase_579\" class=\"edd_download_purchase_form edd_purchase_579\" method=\"post\" action=\"\">\n\n\t\t\n\t\t<div class=\"edd_purchase_submit_wrapper\">\n\t\t\t<button class=\"edd-add-to-cart button orange edd-submit\" data-nonce=\"b7d9a84811\" data-timestamp=\"1784158944\" data-token=\"6135e3aad5ef2e0cb1ce775afead96015b0d4ea29340da979579b90fb60e880b\" data-action=\"edd_add_to_cart\" data-download-id=\"579\" data-variable-price=\"no\" data-price-mode=\"single\" data-price=\"0.00\" ><span class=\"edd-add-to-cart-label\">Gratuit - Dans le panier de la m\u00e9nag\u00e8re<\/span> <span class=\"edd-loading\" aria-label=\"Chargement en cours\"><\/span><\/button><input type=\"submit\" class=\"edd-add-to-cart edd-no-js button orange edd-submit\" name=\"edd_purchase_download\" value=\"Gratuit - Dans le panier de la m\u00e9nag\u00e8re\" data-action=\"edd_add_to_cart\" data-download-id=\"579\" data-variable-price=\"no\" data-price-mode=\"single\" \/><a href=\"https:\/\/www.rundwanderung-lagomera.de\/fr\/checkout\/?nocache=true\" class=\"edd_go_to_checkout button orange edd-submit\" style=\"display:none;\">Voir Panier d&#039;achat<\/a>\n\t\t\t\t\t\t\t<span class=\"edd-cart-ajax-alert\" aria-live=\"assertive\">\n\t\t\t\t\t<span class=\"edd-cart-added-alert\" style=\"display: none;\">\n\t\t\t\t\t\t<svg class=\"edd-icon edd-icon-check\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"28\" viewbox=\"0 0 28 28\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t<path d=\"M26.11 8.844c0 .39-.157.78-.44 1.062L12.234 23.344c-.28.28-.672.438-1.062.438s-.78-.156-1.06-.438l-7.782-7.78c-.28-.282-.438-.673-.438-1.063s.156-.78.438-1.06l2.125-2.126c.28-.28.672-.438 1.062-.438s.78.156 1.062.438l4.594 4.61L21.42 5.656c.282-.28.673-.438 1.063-.438s.78.155 1.062.437l2.125 2.125c.28.28.438.672.438 1.062z\"\/>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\tAjout\u00e9 au panier\t\t\t\t\t<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div><!--end .edd_purchase_submit_wrapper-->\n\n\t\t<input type=\"hidden\" name=\"download_id\" value=\"579\">\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"edd_action\" class=\"edd_action_input\" value=\"add_to_cart\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t<input type=\"hidden\" name=\"trp-form-language\" value=\"fr\"\/><\/form><!--end #edd_purchase_579-->\n\t<\/div><div id=\"panel-524-1-1-2\" class=\"so-panel widget widget_text panel-last-child\" data-index=\"4\" >\t\t\t<div class=\"textwidget\">Tous les autres t\u00e9l\u00e9chargements sont disponibles sur <a href=\"https:\/\/www.rundwanderung-lagomera.de\/fr\/cartes-en-lignehors-ligne\/\">Plans<\/a>.<\/div>\n\t\t<\/div><\/div><\/div><div id=\"pg-524-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-524-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-524-2-0-0\" class=\"so-panel widget widget_text panel-first-child\" data-index=\"5\" ><h3 class=\"widget-title\">Plage de la Guancha<\/h3>\t\t\t<div class=\"textwidget\"><p>Apr\u00e8s un peu plus d&#039;1h nous atteignons la premi\u00e8re petite plage, la &quot;Playa de la Guancha&quot;. De l\u00e0, un chemin bord\u00e9 de pierres sans vis-\u00e0-vis m\u00e8ne dans la vall\u00e9e. Nous le suivons et montons bient\u00f4t le versant gauche pour en faire le tour par derri\u00e8re \u00e0 mi-hauteur. Apr\u00e8s une courte mont\u00e9e en zigzag avec une belle vue sur la vall\u00e9e, nous atteignons un carrefour avec un banc de pause au waypoint 4. Ici, nous tournons \u00e0 gauche, c&#039;est-\u00e0-dire que nous montons d&#039;abord l\u00e9g\u00e8rement en direction du sud. Peu de temps apr\u00e8s, nous descendons en serpentins \u00e9troits jusqu&#039;\u00e0 la plage suivante. En bas dans le lit de la rivi\u00e8re (waypoint 5), nous rencontrons un mur derri\u00e8re lequel se trouve une route que nous suivons jusqu&#039;\u00e0 la plage. <\/p>\n<\/div>\n\t\t<\/div><div id=\"panel-524-2-0-1\" class=\"so-panel widget widget_text\" data-index=\"6\" ><h3 class=\"widget-title\">Plage du Cabrito<\/h3>\t\t\t<div class=\"textwidget\"><p>Une plantation de bananes se trouvait autrefois dans cette vall\u00e9e isol\u00e9e. Aujourd&#039;hui, la \u00ab Playa el Cabrito \u00bb est presque enti\u00e8rement occup\u00e9e par un complexe h\u00f4telier \u00e9cologique. L&#039;ancienne salle des bananes allong\u00e9e, qui est maintenant utilis\u00e9e par l&#039;h\u00f4tel comme salle \u00e0 manger, est clairement visible depuis la plage. <b>Danger:<\/b> L&#039;h\u00f4tel ne propose pas de service de restauration pour les visiteurs ext\u00e9rieurs et ne doit donc pas \u00eatre pr\u00e9vu comme un poste de ravitaillement !<br \/>\nLes grands lacets de notre prochaine ascension sur le flanc de la montagne derri\u00e8re l&#039;h\u00f4tel sont tout aussi clairement visibles. Quittez la plage juste derri\u00e8re l&#039;ancien hall de la banane et marchez sous la paroi rocheuse escarp\u00e9e derri\u00e8re le terrain de l&#039;h\u00f4tel jusqu&#039;au d\u00e9but de l&#039;ascension.<br \/>\nArriv\u00e9s sur la cr\u00eate (env. 200 m\u00e8tres de d\u00e9nivel\u00e9), nous suivons le chemin \u00e0 droite - \u00e0 gauche le chemin ne m\u00e8ne qu&#039;\u00e0 une &quot;impasse&quot;, mais avec une belle vue.<br \/>\nUne autre mont\u00e9e nous emm\u00e8ne \u00e0 environ 380 m\u00e8tres d&#039;altitude, puis nous continuons \u00e0 500 m\u00e8tres d&#039;altitude, o\u00f9 nous rencontrons enfin le village abandonn\u00e9 &quot;Morales&quot; (waypoint 6). L\u00e0, nous suivons les panneaux en direction de Playa de Santiago. D\u00e9sormais c&#039;est une descente tranquille.<br \/>\nNous traversons &quot;Contreras&quot;, un autre village abandonn\u00e9, et apercevons bient\u00f4t les premi\u00e8res maisons de Playa de Santiago au loin. Attention : la perspective d\u00e9ment le fait qu&#039;il reste encore trois &quot;Barrancos&quot; (gorges) de taille moyenne \u00e0 franchir avec des mont\u00e9es et des descentes avant d&#039;arriver \u00e0 destination !<\/p>\n<\/div>\n\t\t<\/div><div id=\"panel-524-2-0-2\" class=\"so-panel widget widget_text panel-last-child\" data-index=\"7\" ><h3 class=\"widget-title\">Plage de Santiago<\/h3>\t\t\t<div class=\"textwidget\"><p>Le chemin vers Playa de Santiago est long car il reste encore de nombreux lacets et mont\u00e9es interm\u00e9diaires \u00e0 franchir peu avant la destination. Certains d&#039;entre eux m\u00e8nent le long de la route goudronn\u00e9e, certains ont des raccourcis plus raides pour les pi\u00e9tons.<br \/>\nLa derni\u00e8re partie du chemin m\u00e8ne le long de l&#039;all\u00e9e devant le terrain de golf jusqu&#039;\u00e0 l&#039;entr\u00e9e du grand complexe h\u00f4telier &quot;Hotel Jard\u00edn Tecina&quot;. L&#039;arr\u00eat de bus pour le retour \u00e0 San Sebasti\u00e1n se trouve un peu plus loin dans le virage de la route principale qui croise notre chemin. Si vous avez r\u00e9serv\u00e9 une nuit\u00e9e dans la partie inf\u00e9rieure de Playa de Santiago ou si vous souhaitez prendre le ferry pour revenir \u00e0 San Sebasti\u00e1n au lieu du bus, vous devez descendre un peu ou encore 1,5 km d&#039;ici.<\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-524-2-1\"  class=\"panel-grid-cell\" ><div id=\"panel-524-2-1-0\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-first-child panel-last-child\" data-index=\"8\" ><div class=\"textwidget\"><p>\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 100%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-524 gallery-columns-1 gallery-size-medium'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href=\"https:\/\/www.rundwanderung-lagomera.de\/wp-content\/uploads\/2016\/01\/rundwanderweg-la-gomera-etappe-6-ausblick-auf-die-playa-de-la-guancha.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"139\" height=\"300\" src=\"https:\/\/www.rundwanderung-lagomera.de\/wp-content\/uploads\/2016\/01\/rundwanderweg-la-gomera-etappe-6-ausblick-auf-die-playa-de-la-guancha-139x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.rundwanderung-lagomera.de\/wp-content\/uploads\/2016\/01\/rundwanderweg-la-gomera-etappe-6-ausblick-auf-die-playa-de-la-guancha-139x300.jpg 139w, https:\/\/www.rundwanderung-lagomera.de\/wp-content\/uploads\/2016\/01\/rundwanderweg-la-gomera-etappe-6-ausblick-auf-die-playa-de-la-guancha-476x1024.jpg 476w, https:\/\/www.rundwanderung-lagomera.de\/wp-content\/uploads\/2016\/01\/rundwanderweg-la-gomera-etappe-6-ausblick-auf-die-playa-de-la-guancha.jpg 640w\" sizes=\"auto, (max-width: 139px) 100vw, 139px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/www.rundwanderung-lagomera.de\/wp-content\/uploads\/2016\/01\/la-gomera-rundwanderweg-etappe-6-playa-de-la-guancha-eingefasster-steinweg.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.rundwanderung-lagomera.de\/wp-content\/uploads\/2016\/01\/la-gomera-rundwanderweg-etappe-6-playa-de-la-guancha-eingefasster-steinweg-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.rundwanderung-lagomera.de\/wp-content\/uploads\/2016\/01\/la-gomera-rundwanderweg-etappe-6-playa-de-la-guancha-eingefasster-steinweg-300x225.jpg 300w, https:\/\/www.rundwanderung-lagomera.de\/wp-content\/uploads\/2016\/01\/la-gomera-rundwanderweg-etappe-6-playa-de-la-guancha-eingefasster-steinweg-768x576.jpg 768w, https:\/\/www.rundwanderung-lagomera.de\/wp-content\/uploads\/2016\/01\/la-gomera-rundwanderweg-etappe-6-playa-de-la-guancha-eingefasster-steinweg.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/www.rundwanderung-lagomera.de\/wp-content\/uploads\/2016\/01\/rundwanderweg-la-gomera-etappe-6-und-wieder-ein-Barranco-zu-durchqueren.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.rundwanderung-lagomera.de\/wp-content\/uploads\/2016\/01\/rundwanderweg-la-gomera-etappe-6-und-wieder-ein-Barranco-zu-durchqueren-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.rundwanderung-lagomera.de\/wp-content\/uploads\/2016\/01\/rundwanderweg-la-gomera-etappe-6-und-wieder-ein-Barranco-zu-durchqueren-300x225.jpg 300w, https:\/\/www.rundwanderung-lagomera.de\/wp-content\/uploads\/2016\/01\/rundwanderweg-la-gomera-etappe-6-und-wieder-ein-Barranco-zu-durchqueren-768x576.jpg 768w, https:\/\/www.rundwanderung-lagomera.de\/wp-content\/uploads\/2016\/01\/rundwanderweg-la-gomera-etappe-6-und-wieder-ein-Barranco-zu-durchqueren.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n<\/p>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Heute ist der letzte Tag unserer Rundwanderung und wir haben mit ca. 21 km die l\u00e4ngste der sechs Etappen vor uns! Unser Tipp: Wer heute rechtzeitig startet, kann am Etappenziel den Bus oder die F\u00e4hre zur\u00fcck nach San Sebasti\u00e1n erreichen \u2013 sprich: wir k\u00f6nnen bei entsprechender \u00dcbernachtungsplanung einen Teil des Gep\u00e4cks im Hotel lassen. Abfahrtszeiten [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,8],"tags":[],"class_list":["post-524","post","type-post","status-publish","format-standard","hentry","category-etappe-6","category-etappen"],"_links":{"self":[{"href":"https:\/\/www.rundwanderung-lagomera.de\/fr\/wp-json\/wp\/v2\/posts\/524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rundwanderung-lagomera.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rundwanderung-lagomera.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rundwanderung-lagomera.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rundwanderung-lagomera.de\/fr\/wp-json\/wp\/v2\/comments?post=524"}],"version-history":[{"count":0,"href":"https:\/\/www.rundwanderung-lagomera.de\/fr\/wp-json\/wp\/v2\/posts\/524\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.rundwanderung-lagomera.de\/fr\/wp-json\/wp\/v2\/media?parent=524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rundwanderung-lagomera.de\/fr\/wp-json\/wp\/v2\/categories?post=524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rundwanderung-lagomera.de\/fr\/wp-json\/wp\/v2\/tags?post=524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}